{"id":34217,"date":"2025-04-28T12:49:34","date_gmt":"2025-04-28T10:49:34","guid":{"rendered":"https:\/\/hannover-living.de\/location\/museum-schloss-herrenhausen\/"},"modified":"2025-10-20T16:54:40","modified_gmt":"2025-10-20T14:54:40","slug":"museum-herrenhausen-slot","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/da\/location\/museum-schloss-herrenhausen\/","title":{"rendered":"Herrenhausen Slotsmuseum"},"template":"","meta":{"loc_subtitle":"Barocke Sch\u00e4tze und Hannovers Geschichte","loc_beschreibung":"<p>Das Museum Schloss Herrenhausen bietet einen tiefen Einblick in die barocke Epoche und die Geschichte Hannovers. In den historischen R\u00e4umlichkeiten des Schlosses werden bedeutende Exponate ausgestellt, die die kulturelle Entwicklung der Region veranschaulichen.<\/p>\n<h2>Historischer Hintergrund<\/h2>\n<p>Das Schloss Herrenhausen wurde im 17. Jahrhundert als Sommerresidenz der Welfen errichtet. W\u00e4hrend des Zweiten Weltkriegs zerst\u00f6rt, erfolgte der Wiederaufbau zwischen 2011 und 2013. Seitdem dient es als Sitz des Museums und eines wissenschaftlichen Tagungszentrums.<\/p>\n<h2>Ausstellungshighlights<\/h2>\n<p>Das Museum pr\u00e4sentiert auf 900 Quadratmetern barocke Kunstwerke, historische Dokumente und Pers\u00f6nlichkeiten wie Gottfried Wilhelm Leibniz und Kurf\u00fcrstin Sophie. Ein besonderes Highlight ist die Originalb\u00fcste von Leibniz, die im Museum ausgestellt ist.<\/p>\n","loc_strasse":"Herrenh\u00e4user Str.","loc_hausnummer":"5","loc_plz":"30419","loc_ort":"Hannover","loc_google_maps":"Museum Schloss Herrenhausen,Herrenh\u00e4user Str. 5,30419 Hannover","loc_telefonnummer":"","loc_stadtteil":"herrenhausen","loc_teaserbild":"42883","loc_teasertext":"Mit dem Schloss Herrenhausen, das als wissenschaftliches Tagungszentrum und Museum genutzt wird, haben die Herrenh\u00e4user G\u00e4rten ihren architektonischen Bezugspunkt zur\u00fcckerhalten.","loc_webseite":"https:\/\/www.hannover.de\/Herrenhausen\/Museum-Schloss-Herrenhausen","loc_360_link":"https:\/\/www.hannover-living.de\/wp-content\/uploads\/panorama\/MuseenHannoveroS.html","loc_facebook":"","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"true","loc_switch_open_show":"true","loc_open_montag":"Geschlossen","loc_open_dienstag":"11:00\u201318:00 Uhr","loc_open_mittwoch":"11:00\u201318:00 Uhr","loc_open_donnerstag":"11:00\u201318:00 Uhr","loc_open_freitag":"11:00\u201318:00 Uhr","loc_open_samstag":"11:00\u201318:00 Uhr","loc_open_sontag":"11:00\u201318:00 Uhr","loc_nachhaltigkeit":"false","loc_galerie":["34221","39130"],"loc_location_art":["museen_galerien_kunstvereien","sightseeing"],"loc_nightlife":[],"loc_freizeit":["museen_galerien","indoor"],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"Museum Schloss Herrenhausen,Herrenh\u00e4user Str. 5,30419 Hannover","loc_admin_google_place_id":"ChIJqV8hcWRzsEcRYN81GpDJTW0","loc_admin_master_id":"250"},"class_list":["post-34217","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/da\/wp-json\/wp\/v2\/location\/34217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/da\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/da\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/da\/wp-json\/wp\/v2\/media?parent=34217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}