{"id":35890,"date":"2025-05-01T13:41:29","date_gmt":"2025-05-01T11:41:29","guid":{"rendered":"https:\/\/hannover-living.de\/stadtteil\/vahrenheide\/"},"modified":"2025-08-12T16:10:53","modified_gmt":"2025-08-12T14:10:53","slug":"vahrenheide","status":"publish","type":"stadtteil","link":"https:\/\/hannover-living.de\/da\/stadtteil\/vahrenheide\/","title":{"rendered":"Vahrenheide"},"template":"","meta":{"dis_headerimage":"https:\/\/hannover-living.de\/wp-content\/uploads\/2025\/05\/Design-ohne-Titel211.png","dis_beschreibung":"Willkommen im Stadtteil Vahrenheide! Im Norden Hannovers gelegen, pr\u00e4sentiert sich Vahrenheide als lebendiges Quartier mit viel Gr\u00fcn und einer multikulturellen Vielfalt. Hier trefft ihr auf eine bunte Mischung aus Wohnsiedlungen, gro\u00dfz\u00fcgigen Parkanlagen und aktiven Nachbarschaften. Ob Sport, Erholung oder kulturelle Begegnungen \u2013 Vahrenheide bietet euch abwechslungsreiche M\u00f6glichkeiten mitten im st\u00e4dtischen Leben.","dis_auswahl":"vahrenheide"},"class_list":["post-35890","stadtteil","type-stadtteil","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/da\/wp-json\/wp\/v2\/stadtteil\/35890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/da\/wp-json\/wp\/v2\/stadtteil"}],"about":[{"href":"https:\/\/hannover-living.de\/da\/wp-json\/wp\/v2\/types\/stadtteil"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/da\/wp-json\/wp\/v2\/media?parent=35890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}