{"id":35137,"date":"2025-04-28T13:34:43","date_gmt":"2025-04-28T11:34:43","guid":{"rendered":"https:\/\/hannover-living.de\/location\/die-aegidienkirche\/"},"modified":"2025-07-04T07:58:12","modified_gmt":"2025-07-04T05:58:12","slug":"la-iglesia-de-santa-eudalia","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/es\/location\/die-aegidienkirche\/","title":{"rendered":"La Aegidienkirche"},"template":"","meta":{"loc_subtitle":"T\u00e4glich l\u00e4uten viermal die Glocken","loc_beschreibung":"<h5>Von Heinrich des L\u00f6wen bis 1943<\/h5>\n<p>Eine Kirche ohne Dach l\u00e4sst Raum f\u00fcr Fantasie. Doch zun\u00e4chst ist davon gar nicht soviel n\u00f6tig. Es geht ums Erinnern. Von dieser gotischen Hallenkirche ging in Hannover die Reformation aus. Erstmals urkundlich erw\u00e4hnt wurde die Aegidienkirche schon 1163. Das war zu einem Hoftag Heinrich des L\u00f6wen. Vermutlich schon im 10. Jahrhundert stand hier eine kleine Kapelle. Sie wurde dann im 12. Jahrhundert durch eine romanische Basilika ersetzt. Sp\u00e4ter haben Georg Friedrich Laves und Conrad Wilhelm Hase ihre Bau-Akzente gesetzt. Dann aber kam die Nacht zum 9. Oktober 1943. Im Bombenhagel des Zweiten Weltkriegs ging die Kirche unter. Es blieben nur die Au\u00dfenmauern mit ihren typischen dreieckigen Seitengiebeln sowie ein Teil des Turms stehen.<\/p>\n<p>W\u00e4hrend Hannover nach dem Krieg wieder aufgebaut wurde (siehe Stadtmodelle im Neuen Rathaus), entschied man sich, diese Kirche zum Mahnmal zu machen. Als Gedenkst\u00e4tte f\u00fcr die Opfer von Kriegen und Gewalt steht sie seit 1952 f\u00fcr Veranstaltungen offen. Viermal t\u00e4glich l\u00e4uten die Glocken \u2013 um 9.05, 12.05, 15.05 und 18.05 Uhr. Als besonderes Geschenk der Partnerstadt Hiroshima wird immer am 6. August die Friedensglocke von 1985 angesto\u00dfen. So wird an den Atombombenabwurf gedacht (siehe auch Hiroshima Gedenkhain).<\/p>\n<h5>Die Erinnerungskultur ist lebendig<\/h5>\n<p>Der 9. Oktober aber dient der Erinnerung an den Bombenhagel britischer Bomber \u00fcber Hannover. 1245 Menschen kamen damals direkt ums Leben. Wie das Ursel Fuchs in der S\u00fcdstadt damals als Kind erlebte, hielt sie in ihrem Buch \u201eTr\u00fcmmer, Trauer, Traumata\u201c fest (Reihe Schriften zur Erinnerungskultur in Hannover, Band 7).<\/p>\n<p>Wer dann n\u00e4her die Skulptur \u201eDemut\u201c im Innenraum betrachtet, geschaffen vom hannoverschen Bildhauer Prof. Kurt Lehmann, und gen Himmel blickt, findet Raum f\u00fcr Fantasie und zum Nachdenken. Es ist ein ehrw\u00fcrdiger, mahnender Ort mit einem gro\u00dfen Fenster nach oben.<\/p>\n","loc_strasse":"Aegidienkirchhof ","loc_hausnummer":"1","loc_plz":"30159","loc_ort":"Hannover","loc_google_maps":"Die Aegidienkirche,Aegidienkirchhof 1, 30159 Hannover, Deutschland","loc_telefonnummer":"","loc_stadtteil":"mitte","loc_teaserbild":"35138","loc_teasertext":"Die im Zweiten Weltkrieg weitgehend zerst\u00f6rte Aegidienkirche in Hannover dient seit 1954 als Mahnmal f\u00fcr die Opfer von Krieg und Gewalt.","loc_webseite":"","loc_360_link":"","loc_facebook":"","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"false","loc_switch_open_show":"false","loc_open_montag":"","loc_open_dienstag":"","loc_open_mittwoch":"","loc_open_donnerstag":"","loc_open_freitag":"","loc_open_samstag":"","loc_open_sontag":"","loc_nachhaltigkeit":"false","loc_galerie":[],"loc_location_art":["sightseeing"],"loc_nightlife":[],"loc_freizeit":["sehenswuerdigkeiten_highlights"],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"Die Aegidienkirche,Aegidienkirchhof 1, 30159 Hannover, Deutschland","loc_admin_google_place_id":"ChIJvxUCnbZ0sEcRgaL6XHL05a4","loc_admin_master_id":"853"},"class_list":["post-35137","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/location\/35137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/media?parent=35137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}