{"id":35902,"date":"2025-05-01T13:41:51","date_gmt":"2025-05-01T11:41:51","guid":{"rendered":"https:\/\/hannover-living.de\/stadtteil\/oststadt\/"},"modified":"2025-08-12T16:05:02","modified_gmt":"2025-08-12T14:05:02","slug":"ciudad-oriental","status":"publish","type":"stadtteil","link":"https:\/\/hannover-living.de\/es\/stadtteil\/oststadt\/","title":{"rendered":"Ciudad oriental"},"template":"","meta":{"dis_headerimage":"https:\/\/hannover-living.de\/wp-content\/uploads\/2025\/05\/Design-ohne-Titel91.jpg","dis_beschreibung":"Willkommen im Stadtteil Oststadt! Im Nordosten \r\nHannovers gelegen, grenzt die Oststadt an die Eilenriede und erstreckt sich bis zur Hamburger Allee. Hier verbindet die Lister Meile als lebendige Fu\u00dfg\u00e4ngerzone den Hauptbahnhof mit dem Lister Platz und l\u00e4dt zum Bummeln ein. Das Kulturzentrum Pavillon bietet vielf\u00e4ltige Veranstaltungen, w\u00e4hrend der Wei\u00dfekreuzplatz zum Verweilen einl\u00e4dt. Historische Bauten, moderne Einrichtungen und die N\u00e4he zur Natur machen die Oststadt zu einem attraktiven Wohn- und Arbeitsort.","dis_auswahl":"hannover-ost"},"class_list":["post-35902","stadtteil","type-stadtteil","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/stadtteil\/35902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/stadtteil"}],"about":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/types\/stadtteil"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/media?parent=35902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}