{"id":40944,"date":"2025-07-04T15:16:35","date_gmt":"2025-07-04T13:16:35","guid":{"rendered":"https:\/\/hannover-living.de\/veranstaltungen\/very-british-auf-den-spuren-der-personalunion\/"},"modified":"2025-11-12T21:16:29","modified_gmt":"2025-11-12T19:16:29","slug":"muy-britanico-tras-las-huellas-de-la-union-personal","status":"publish","type":"veranstaltungen","link":"https:\/\/hannover-living.de\/es\/veranstaltungen\/very-british-auf-den-spuren-der-personalunion\/","title":{"rendered":"Muy brit\u00e1nico: tras la pista de la uni\u00f3n personal"},"author":0,"template":"","meta":{"ev_date":{"rrule":"","dates":[{"start":"1789221600"},{"start":"1790431200"}]},"ev_beschreibung":"<p>Mit dem britischen Thronantritt von Kurf\u00fcrst Georg Ludwig im Jahr 1714 begann die \u00c4ra der Personalunion zwischen Hannover und Gro\u00dfbritannien. \u00dcber mehr als ein Jahrhundert hinweg waren die hannoverschen Herrscher gleichzeitig K\u00f6nige von England. Trotz politischer Trennung entstanden enge Verbindungen in Wissenschaft, Landwirtschaft und Kunst. Erst 1837 endete diese besondere Epoche, als Wilhelm IV. ohne m\u00e4nnliche Erben blieb und das welfische Erbrecht eine weibliche Thronfolge ausschloss.<\/p>\n<p>Die Stadtf\u00fchrung\u00a0<strong>\u201eHannover: Very British \u2013 auf den Spuren der Personalunion\u201c<\/strong>\u00a0l\u00e4dt Euch ein, in diese faszinierende Zeit einzutauchen. Startpunkt ist das gem\u00fctliche Teest\u00fcbchen am Ballhof, wo der traditionelle\u00a0<strong>\u201eWelfentee\u201c<\/strong>\u00a0serviert wird \u2013 eine Hommage an das Haus Hannover und seine enge Beziehung zu Gro\u00dfbritannien.<\/p>\n<p>Den Abschluss bildet ein Besuch in einem irischen Pub in der Altstadt, wo wahlweise ein <strong>Guinness oder ein alkoholfreies Getr\u00e4nk<\/strong>\u00a0gereicht wird.<\/p>\n","ev_galerie":[],"ev_ticket":"https:\/\/www.hannover-tourismus.de\/very-british\/#\/","ev_poster":"","ev_veranstaltungsheader":"","ev_youtube":"","ev_kategorie":["stadttouren"],"ev_teaserbild":"32811","ev_teasertext":"Die Stadtf\u00fchrung \u201eHannover: Very British \u2013 auf den Spuren der Personalunion\u201c l\u00e4dt Euch ein, in die britische Zeit einzutauchen. ","ev_seo_name":"Ballhof","ev_seo_strasse":"Ballhofplatz 5","ev_seo_plz":"30159","ev_seo_ort":"Hannover"},"class_list":["post-40944","veranstaltungen","type-veranstaltungen","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/veranstaltungen\/40944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/veranstaltungen"}],"about":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/types\/veranstaltungen"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/es\/wp-json\/wp\/v2\/media?parent=40944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}