{"id":34329,"date":"2025-04-28T12:50:36","date_gmt":"2025-04-28T10:50:36","guid":{"rendered":"https:\/\/hannover-living.de\/location\/frioli-die-eismanufaktur\/"},"modified":"2025-12-08T17:38:31","modified_gmt":"2025-12-08T15:38:31","slug":"frioli-la-fabrique-de-glaces","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/fr\/location\/frioli-die-eismanufaktur\/","title":{"rendered":"Frioli - la manufacture de glace"},"template":"","meta":{"loc_subtitle":"Eiscaf\u00e9 und mobile Eisfreude in Hannover","loc_beschreibung":"<p>Bei Frioli in Hannover-Linden erwartet euch eine wahre Eis-Oase, in der handgemachte Eiskreationen und h\u00f6chste Bio-Qualit\u00e4t im Mittelpunkt stehen. Ob ihr im funktionalen Innenraum oder auf der wundersch\u00f6nen Blumenterrasse Platz nehmt \u2013 hier genie\u00dft ihr Eis, das mit viel Liebe und nat\u00fcrlichen Zutaten hergestellt wird.<\/p>\n<p>Besonders erfreulich ist der wachsende Anteil an pflanzlichen Eissorten, die ganz ohne k\u00fcnstliche Bindemittel auskommen und auf reinen Fr\u00fcchten basieren. Klassische Sorten wie Schokolade oder Nussvariationen werden auf alternativen Basen wie Hafer oder Mandel zubereitet und bieten damit f\u00fcr jeden Geschmack das Richtige.<\/p>\n<p>Auch Kaffee-Liebhaber kommen bei Frioli auf ihre Kosten: Der nachhaltige Mulembe-Kaffee aus Hannover-Limmer \u00fcberzeugt mit einem Cupping Score von \u00fcber 83 und geh\u00f6rt zu den Spezialit\u00e4tenkaffees. Mit dem Motto \u201eweniger Zucker, mehr Geschmack\u201c k\u00f6nnt ihr euch auf intensiven Genuss freuen, der ganz ohne k\u00fcnstliche Aromen, Farbstoffe oder Palmfett auskommt.<\/p>\n<p>Besonders praktisch: Frioli bietet euch \u00fcber 20 Sorten am Tresen und eine noch gr\u00f6\u00dfere Auswahl f\u00fcr Zuhause.<\/p>\n<p>Kein Wunder, dass Frioli zu den 20 besten Eisdielen Deutschlands geh\u00f6rt \u2013 lasst euch diesen Genuss nicht entgehen!<\/p>\n<p>&nbsp;<\/p>\n","loc_strasse":"Stephanusstra\u00dfe","loc_hausnummer":"8","loc_plz":"30449","loc_ort":"Hannover","loc_google_maps":"Frioli \u2013 die Eismanufaktur,Stephanusstra\u00dfe 8,30449 Hannover","loc_telefonnummer":"www.frioli.de","loc_stadtteil":"linden-mitte","loc_teaserbild":"41722","loc_teasertext":"Genie\u00dft k\u00f6stliches Eis im Eiscaf\u00e9 oder bucht einen Eiswagen f\u00fcr eure Feier \u2013 Frioli bringt euch puren Eisgenuss!","loc_webseite":"www.frioli.de","loc_360_link":"","loc_facebook":"https:\/\/www.facebook.com\/friolidieeismanufaktur","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"true","loc_art_der_kueche":["cafe_breakfast","eisdiele"],"loc_ambiente":"gem\u00fctlich, italienisch","loc_switch_google_preisklasse":"true","loc_preisklasse":"\u20ac\u20ac\u20ac","loc_unser_tipp":"Veganes Schokoladeneis, Lavendeleis, Schwarzw\u00e4lder Kirscheis, Vanilleeis mit Tahitensis Vanille","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"true","loc_switch_open_show":"true","loc_open_montag":"13:00\u201318:00 Uhr","loc_open_dienstag":"13:00\u201318:00 Uhr","loc_open_mittwoch":"13:00\u201318:00 Uhr","loc_open_donnerstag":"13:00\u201318:00 Uhr","loc_open_freitag":"13:00\u201318:00 Uhr","loc_open_samstag":"10:00\u201318:00 Uhr","loc_open_sontag":"13:00\u201318:00 Uhr","loc_nachhaltigkeit":"false","loc_galerie":["34331","34332","34333","41722"],"loc_location_art":["restaurant"],"loc_nightlife":[],"loc_freizeit":[],"loc_events_show":"false","loc_rest_show":"true","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"info@frioli.de","loc_admin_google_adress":"Frioli \u2013 die Eismanufaktur,Stephanusstra\u00dfe 8,30449 Hannover","loc_admin_google_place_id":"ChIJF8RGuJR0sEcRe1j2NtQ8weA","loc_admin_master_id":"743"},"class_list":["post-34329","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/location\/34329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/media?parent=34329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}