{"id":34893,"date":"2025-04-28T13:30:49","date_gmt":"2025-04-28T11:30:49","guid":{"rendered":"https:\/\/hannover-living.de\/location\/karikaturmuseum-wilhelm-busch\/"},"modified":"2025-08-29T15:43:39","modified_gmt":"2025-08-29T13:43:39","slug":"musee-de-la-caricature-wilhelm-busch","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/fr\/location\/karikaturmuseum-wilhelm-busch\/","title":{"rendered":"Mus\u00e9e de la caricature Wilhelm Busch"},"template":"","meta":{"loc_subtitle":"Karikatur und Zeichenkunst","loc_beschreibung":"<p>Mitten im Georgengarten liegt das Wilhelm Busch Museum, das Deutsche Museum f\u00fcr Karikatur und Zeichenkunst. Hier kann in die Entwicklung der Karikaturkunst eingetaucht und die Werke bekannter Karikaturisten aus verschiedenen Epochen erkundet werden. Das Karikaturmuseum pr\u00e4sentiert eine Vielzahl von Stilen und Techniken, die in den Karikaturen zum Ausdruck kommen, und enth\u00fcllt die satirischen Botschaften hinter den Bildern.<\/p>\n<p>Neben der beeindruckenden Dauerausstellung beherbergt das Karikaturmuseum Wilhelm Busch regelm\u00e4\u00dfig Sonderausstellungen zu verschiedenen Themen und K\u00fcnstlern. Diese Ausstellungen erweitern das Spektrum der Karikaturen und bieten den Besuchern die M\u00f6glichkeit, verschiedene Facetten der Karikaturkunst zu entdecken. So sind Ausstellungen gro\u00dfer humoristischer, satirischer K\u00fcnstler wie Wilhelm Busch, Loriot und Jean-Jacques Semp\u00e9, von William Hogarth bis Marie Marcks und Friedrich Karl Waechter hier zu sehen, aber auch von Kinderbuchillustratoren wie Axel Scheffler oder Eric Carle.<\/p>\n<p>Das Wilhelm Busch Museum bietet zudem F\u00fchrungen, interaktive Workshops und spannende Veranstaltungen f\u00fcr Kinder und Erwachsene an. Diese Programme erm\u00f6glichen es den Besuchern, auf unterhaltsame und lehrreiche Weise in die Welt der Karikatur einzutauchen.<\/p>\n","loc_strasse":"Georgengarten","loc_hausnummer":"1","loc_plz":"30167","loc_ort":"Hannover","loc_google_maps":"Karikaturmuseum Wilhelm Busch,Georgengarten 1,30167 Hannover","loc_telefonnummer":"","loc_stadtteil":"nordstadt","loc_teaserbild":"41877","loc_teasertext":"Im Karikaturmuseum Hannover erwartet Euch eine Sammlung satirischer Kunst von 1600 bis heute \u2013 inklusive Sonderausstellungen und Workshops.","loc_webseite":"https:\/\/www.karikatur-museum.de\/","loc_360_link":"https:\/\/www.hannover-living.de\/wp-content\/uploads\/panorama\/MuseenHannoveroS.html","loc_facebook":"https:\/\/de-de.facebook.com\/KarikaturMuseum\/","loc_instagram":"https:\/\/www.instagram.com\/wilhelm_busch_museum\/","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"true","loc_switch_open_show":"true","loc_open_montag":"Geschlossen","loc_open_dienstag":"11:00\u201317:00 Uhr","loc_open_mittwoch":"11:00\u201317:00 Uhr","loc_open_donnerstag":"11:00\u201317:00 Uhr","loc_open_freitag":"11:00\u201317:00 Uhr","loc_open_samstag":"11:00\u201317:00 Uhr","loc_open_sontag":"11:00\u201317:00 Uhr","loc_nachhaltigkeit":"false","loc_galerie":[],"loc_location_art":["museen_galerien_kunstvereien"],"loc_nightlife":[],"loc_freizeit":["museen_galerien"],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"Karikaturmuseum Wilhelm Busch,Georgengarten 1,30167 Hannover","loc_admin_google_place_id":"ChIJuX0HadU7ZUERK4NaX0friuo","loc_admin_master_id":"225"},"class_list":["post-34893","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/location\/34893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/media?parent=34893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}