{"id":43788,"date":"2025-11-12T21:16:50","date_gmt":"2025-11-12T19:16:50","guid":{"rendered":"https:\/\/hannover-living.de\/veranstaltungen\/stadtteilfuehrung-durch-linden\/"},"modified":"2025-11-12T21:16:50","modified_gmt":"2025-11-12T19:16:50","slug":"visite-guidee-du-quartier-linden-2","status":"publish","type":"veranstaltungen","link":"https:\/\/hannover-living.de\/fr\/veranstaltungen\/stadtteilfuehrung-durch-linden\/","title":{"rendered":"Visite guid\u00e9e du quartier de Linden"},"author":0,"template":"","meta":{"ev_date":{"rrule":"","dates":[{"start":"1789146000"},{"start":"1791565200"}]},"ev_beschreibung":"<h3>Gef\u00fchrte Stadttour durch Hannovers kreatives Viertel<\/h3>\n<p>Begebt euch auf eine spannende Entdeckungsreise durch Linden, einen der lebendigsten und kulturell vielf\u00e4ltigsten Stadtteile Hannovers!<\/p>\n<p>Auf dieser gef\u00fchrten Tour erlebt ihr das besondere Flair des Viertels, das f\u00fcr seine dynamische Kunstszene, alternative Kultur und sein reiches historisches Erbe bekannt ist.<\/p>\n<p>Begleitet von erfahrenen G\u00e4stef\u00fchrerinnen und G\u00e4stef\u00fchrern erfahrt ihr, wie Geschichte und Moderne in Linden auf faszinierende Weise verschmelzen.<\/p>\n<p>Die Tour startet auf der Limmerstra\u00dfe, dem pulsierenden Zentrum Lindens, wo euch eine lebhafte Mischung aus Caf\u00e9s, Gesch\u00e4ften und Kneipen erwartet. Weiter geht es zum Lindener Marktplatz, dem historischen Herz des Viertels, und schlie\u00dflich zum Faustgel\u00e4nde, einem ehemaligen Fabrikkomplex, der heute ein bedeutendes Kulturzentrum ist.<\/p>\n<p>Entdeckt die versteckten Ecken dieses kreativen Stadtteils und erlebt seine einzigartige Atmosph\u00e4re hautnah!<\/p>\n<p>Weitere Infos <a href=\"https:\/\/welcome.visit-hannover.com\/HannoverErlebnisbausteine\/experience?date_unknown=1&amp;doSearch=1&amp;reset=1\">hier<\/a>.<\/p>\n","ev_galerie":["Array"],"ev_ticket":"https:\/\/www.hannover-tourismus.de\/stadtteilfuehrung-linden\/#\/","ev_poster":"","ev_veranstaltungsheader":"43792","ev_youtube":"","ev_kategorie":["kunst_kultur","sonstiges"],"ev_teaserbild":"43792","ev_teasertext":"Erlebt die Limmerstra\u00dfe, den Lindener Marktplatz und das Faustgel\u00e4nde auf einer gef\u00fchrten Stadttour durch dieses lebendige und kulturell vielf\u00e4ltige Viertel.","ev_seo_name":"Theater am K\u00fcchengarten","ev_seo_strasse":"Am K\u00fcchengarten 3-5","ev_seo_plz":"30449","ev_seo_ort":"Hannover"},"class_list":["post-43788","veranstaltungen","type-veranstaltungen","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/veranstaltungen\/43788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/veranstaltungen"}],"about":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/types\/veranstaltungen"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/fr\/wp-json\/wp\/v2\/media?parent=43788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}