{"id":35887,"date":"2025-05-01T13:40:40","date_gmt":"2025-05-01T11:40:40","guid":{"rendered":"https:\/\/hannover-living.de\/stadtteil\/waldhausen\/"},"modified":"2025-08-12T16:11:34","modified_gmt":"2025-08-12T14:11:34","slug":"%e3%83%b4%e3%82%a1%e3%83%ab%e3%83%88%e3%83%8f%e3%82%a6%e3%82%bc%e3%83%b3","status":"publish","type":"stadtteil","link":"https:\/\/hannover-living.de\/ja\/stadtteil\/waldhausen\/","title":{"rendered":"\u30f4\u30a1\u30eb\u30c8\u30cf\u30a6\u30bc\u30f3"},"template":"","meta":{"dis_headerimage":"https:\/\/hannover-living.de\/wp-content\/uploads\/2025\/04\/HL-Header-Stadtteile5.png","dis_beschreibung":"Willkommen im Stadtteil Waldhausen! Im S\u00fcden Hannovers gelegen, zeigt sich Waldhausen als charmantes Wohnviertel mit ruhigem Flair und viel Gr\u00fcn drumherum. Hier erwarten euch elegante Villen, idyllische Stra\u00dfen und eine entspannte Atmosph\u00e4re \u2013 perfekt zum Durchatmen und Wohlf\u00fchlen. Wer urbanes Leben in ruhiger Lage sucht und dabei die N\u00e4he zum Maschsee und zur Eilenriede sch\u00e4tzt, findet in Waldhausen sein ganz pers\u00f6nliches St\u00fcck Hannover.","dis_auswahl":"waldhausen"},"class_list":["post-35887","stadtteil","type-stadtteil","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/ja\/wp-json\/wp\/v2\/stadtteil\/35887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/ja\/wp-json\/wp\/v2\/stadtteil"}],"about":[{"href":"https:\/\/hannover-living.de\/ja\/wp-json\/wp\/v2\/types\/stadtteil"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/ja\/wp-json\/wp\/v2\/media?parent=35887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}