{"id":34556,"date":"2025-04-28T12:52:57","date_gmt":"2025-04-28T10:52:57","guid":{"rendered":"https:\/\/hannover-living.de\/location\/biergarten-lister-turm\/"},"modified":"2025-08-29T15:37:25","modified_gmt":"2025-08-29T13:37:25","slug":"%eb%b9%84%ec%96%b4%ea%b0%80%eb%93%a0-%eb%a6%ac%ec%8a%a4%ed%84%b0-%ed%83%80%ec%9b%8c","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/ko\/location\/biergarten-lister-turm\/","title":{"rendered":"\ub9ac\uc2a4\ud130 \ud130\ub984 \ube44\uc5b4 \uac00\ub4e0"},"template":"","meta":{"loc_subtitle":"Einer der beliebtesten und gr\u00f6\u00dften Bierg\u00e4rten","loc_beschreibung":"<p>Der Biergarten Lister Turm ist seit 23 Jahren einer der beliebtesten und gr\u00f6\u00dften Hannovers, mitten in der Stadt Hannover gelegen, mit Bayrischen und Norddeutschen Bieren und einem reichhaltigen Getr\u00e4nkeangebot.<\/p>\n<p>Auch f\u00fcr das leibliche Wohl ist gesorgt: Ein Grillbuffet mit Spezialit\u00e4ten und Gyros sowie eine bayerische \u201eSchmankerl Bude\u201c bieten sich an. Wem das nicht gen\u00fcgt, der kann sich auch auf der Terrasse des Restaurants Odysseus bedienen lassen.<\/p>\n","loc_strasse":"Walderseestra\u00dfe","loc_hausnummer":"100","loc_plz":"30177","loc_ort":"Hannover","loc_google_maps":"Lister Turm Biergarten,Walderseestra\u00dfe 100,30177 Hannover","loc_telefonnummer":"","loc_stadtteil":"list","loc_teaserbild":"41797","loc_teasertext":"Entdecke den Biergarten Lister Turm \u2013 Hannovers Treffpunkt f\u00fcr Bierliebhaber. Genie\u00dfe neben Bieren, ein reichhaltiges Getr\u00e4nkeangebot sowie Leckereien auf der Terrasse des Restaurants Odysseus.","loc_webseite":"https:\/\/www.lister-turm-biergarten-hannover.de\/","loc_360_link":"","loc_facebook":"https:\/\/www.facebook.com\/listerturmbiergarten","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":["biergarten"],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"true","loc_switch_open_show":"true","loc_open_montag":"15:00\u201322:00 Uhr","loc_open_dienstag":"15:00\u201322:00 Uhr","loc_open_mittwoch":"15:00\u201322:00 Uhr","loc_open_donnerstag":"15:00\u201322:00 Uhr","loc_open_freitag":"15:00\u201322:00 Uhr","loc_open_samstag":"12:00\u201322:00 Uhr","loc_open_sontag":"12:00\u201322:00 Uhr","loc_nachhaltigkeit":"false","loc_galerie":[],"loc_location_art":["restaurant"],"loc_nightlife":[],"loc_freizeit":[],"loc_events_show":"false","loc_rest_show":"true","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"info@lister-turm.de","loc_admin_google_adress":"Biergarten Lister Turm,Walderseestra\u00dfe 100,30177 Hannover","loc_admin_google_place_id":"ChIJayc1vlRzsEcRxemj1s1x1AE","loc_admin_master_id":"425"},"class_list":["post-34556","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/ko\/wp-json\/wp\/v2\/location\/34556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/ko\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/ko\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/ko\/wp-json\/wp\/v2\/media?parent=34556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}