{"id":34212,"date":"2025-04-28T12:49:33","date_gmt":"2025-04-28T10:49:33","guid":{"rendered":"https:\/\/hannover-living.de\/location\/kreuzkirche\/"},"modified":"2025-10-20T16:55:00","modified_gmt":"2025-10-20T14:55:00","slug":"kosciol-krzyzowy","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/pl\/location\/kreuzkirche\/","title":{"rendered":"Ko\u015bci\u00f3\u0142 \u015awi\u0119tego Krzy\u017ca"},"template":"","meta":{"loc_subtitle":" Gotisches Kleinod mit \u00fcber 690 Jahren Geschichte","loc_beschreibung":"<p>Die Kreuzkirche Hannover z\u00e4hlt zu den \u00e4ltesten Kirchen der Stadt und ist ein herausragendes Beispiel gotischer Architektur. Gelegen im idyllischen Kreuzkirchenviertel der Altstadt, bietet sie eine beeindruckende Mischung aus historischer Bedeutung, kultureller Vielfalt und spiritueller Tiefe.<br \/>\nhannover.de<\/p>\n<h2>Baugeschichte und Architektur<\/h2>\n<p>Die Kreuzkirche wurde im Jahr 1333 als Kirche St. Spiritus et Crucis geweiht. Sie entstand aus einer Abspaltung der Marktkirchengemeinde und diente zun\u00e4chst als Pfarrei der Marktkirche. Der Bau erfolgte als einschiffige, gotische Hallenkirche mit Kreuzgew\u00f6lben und einem 5\/8-Chor. Im Laufe der Jahrhunderte erfuhr die Kirche zahlreiche Umbauten und Erweiterungen.<\/p>\n<p>1496\/1497 wurde an der Nordseite des Kirchenschiffs die St. Annenkapelle angebaut, die heute noch einige historische Elemente beherbergt, wie einen Stein mit dem Stadtwappen von Hannover. Im 17. Jahrhundert wurde eine pr\u00e4chtige Grabkapelle f\u00fcr Johann Duve an die S\u00fcdseite des Chors angebaut. Die Turmspitze der Kirche wurde 1630 bei einem Sturm zerst\u00f6rt und 1652\/1653 auf Initiative und durch Finanzierung von Johann Duve als barocker Turm wieder errichtet.<\/p>\n<p>W\u00e4hrend des Zweiten Weltkriegs wurde die Kreuzkirche bei einem der gro\u00dfen Luftangriffe auf Hannover bis auf Mauern, Dachstuhl und Duvekapelle zerst\u00f6rt. Sie wurde zwischen 1959 und 1961 durch Ernst Witt wieder aufgebaut, allerdings ohne das urspr\u00fcngliche Seitenschiff und die Annenkapelle. An der Nordseite wurde 1961 eine kleine Sakristei angef\u00fcgt.<\/p>\n<p><strong>Kunstwerke und Ausstattung<\/strong><\/p>\n<p>Im Inneren der Kreuzkirche befinden sich bedeutende Kunstwerke. Besonders hervorzuheben ist das Altargem\u00e4lde von Lucas Cranach d. \u00c4., das urspr\u00fcnglich f\u00fcr die Schlosskirche geschaffen wurde und nach deren Zerst\u00f6rung in die Kreuzkirche \u00fcberf\u00fchrt wurde. Das bronzene Taufbecken aus dem 15. Jahrhundert ist ein weiteres Highlight der Ausstattung.<\/p>\n<p>Die Kirche beherbergt zudem den \u00e4ltesten Grabstein der Stadt Hannover mit der Inschrift f\u00fcr Thidericus de Rintelen, der 1321 verstarb. Drei gerettete Messing-Kronleuchter erinnern an die im Krieg zerst\u00f6rte Aegidienkirche.<\/p>\n<p>Musikalisches Zentrum<\/p>\n<p>Die Kreuzkirche ist nicht nur ein Ort des Gebets, sondern auch ein Zentrum f\u00fcr Kirchenmusik. Die Akustik des Raumes eignet sich besonders f\u00fcr Chor- und Instrumentalkonzerte. Die 2011 renovierte Orgel sorgt mit ihrem warmen Klang f\u00fcr eindrucksvolle musikalische Erlebnisse.<\/p>\n<p>Regelm\u00e4\u00dfig finden in der Kirche Konzerte, Lesungen und Diskussionsrunden statt. Die Veranstaltungen reichen von klassischen Orchesterkonzerten \u00fcber Klezmer-Abende bis hin zu modernen Musikdarbietungen. Die hervorragende Akustik und die besondere Atmosph\u00e4re machen die Kreuzkirche zu einem beliebten Veranstaltungsort.<\/p>\n","loc_strasse":"Kreuzkirchhof","loc_hausnummer":"3","loc_plz":"30159","loc_ort":"Hannover","loc_google_maps":"Kreuzkirche,Kreuzkirchhof 3,30159 Hannover","loc_telefonnummer":"","loc_stadtteil":"region","loc_teaserbild":"42891","loc_teasertext":"Die Kreuzkirche Hannover vereint gotische Architektur mit kultureller Vielfalt \u2013 ein Ort f\u00fcr Geschichte, Musik und Begegnung.","loc_webseite":"https:\/\/www.visit-hannover.com\/Sehensw%C3%BCrdigkeiten-Stadttouren\/Sehensw%C3%BCrdigkeiten\/Historische-Bauten\/Kirchen-in-Hannover\/Kreuzkirche","loc_360_link":"https:\/\/360.hannover-living.de\/wp-content\/uploads\/panorama\/RundgangKirchenKK.html","loc_facebook":"","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"false","loc_switch_open_show":"false","loc_open_montag":"","loc_open_dienstag":"","loc_open_mittwoch":"","loc_open_donnerstag":"","loc_open_freitag":"","loc_open_samstag":"","loc_open_sontag":"","loc_nachhaltigkeit":"false","loc_galerie":["42891"],"loc_location_art":["sightseeing"],"loc_nightlife":[],"loc_freizeit":["sehenswuerdigkeiten_highlights"],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"Kreuzkirche,Kreuzkirchhof 3,30159 Hannover","loc_admin_google_place_id":"ChIJ2_Bcsrt0sEcRAG0zTIYh-iU","loc_admin_master_id":"844"},"class_list":["post-34212","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/location\/34212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/media?parent=34212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}