{"id":34240,"date":"2025-04-28T12:49:44","date_gmt":"2025-04-28T10:49:44","guid":{"rendered":"https:\/\/hannover-living.de\/location\/buedchen-an-der-u-bahnhaltestelle-lister-platz\/"},"modified":"2025-12-08T17:36:28","modified_gmt":"2025-12-08T15:36:28","slug":"budka-przy-stacji-metra-lister-platz","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/pl\/location\/buedchen-an-der-u-bahnhaltestelle-lister-platz\/","title":{"rendered":"Ma\u0142y sklep na stacji metra Lister Platz"},"template":"","meta":{"loc_subtitle":" ","loc_beschreibung":"<h3>Perfekte Anlaufstelle f\u00fcr Pendler und Stadtteilbewohner<\/h3>\n<p>Der Kiosk mit der offiziellen Adresse Jakobistra\u00dfe 2, direkt am Nahverkehrsknotenpunkt Lister Platz, ist ein praktischer Anlaufpunkt f\u00fcr Pendler, Sch\u00fcler, Touristen und Stadtteilbewohnerinnen und Bewohner.<\/p>\n<p>Direkt am Auf- und Abgang der U-Bahn gelegen, bietet er schnellen Zugang zu allem, was das Herz begehrt. Neben dem vielversprechend gef\u00fcllten Verkaufsfenster stehen K\u00fchlschr\u00e4nke voller Getr\u00e4nke wie Soft- und Energiedrinks oder dem Feierabendbierchen.<\/p>\n<p>Wer sich die Wartezeit am U-Bahnhof klassisch vertreiben m\u00f6chte, greift zu einer der vielen Zeitschriften oder Magazine. Und auch die Fahrkarte kann man dort noch schnell erwerben.<\/p>\n","loc_strasse":"Jakobistra\u00dfe","loc_hausnummer":"2","loc_plz":"30163","loc_ort":"Hannover","loc_google_maps":"B\u00fcdchen an der U-Bahnhaltestelle Lister Platz,Jakobistra\u00dfe 2,30163 Hannover","loc_telefonnummer":"","loc_stadtteil":"list","loc_teaserbild":"41713","loc_teasertext":"Versorgen im Vorbeigehen. Am zentralen Knotenpunkt gelegen, ist das B\u00fcdchen an der U-Bahn-Haltestelle \u201eLister Platz\u201c ein fester Bestandteil des urbanen Lister Lebens.","loc_webseite":"","loc_360_link":"","loc_facebook":"","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"true","loc_switch_open_show":"false","loc_open_montag":"","loc_open_dienstag":"","loc_open_mittwoch":"","loc_open_donnerstag":"","loc_open_freitag":"","loc_open_samstag":"","loc_open_sontag":"","loc_nachhaltigkeit":"false","loc_galerie":[],"loc_location_art":["kiosk"],"loc_nightlife":[],"loc_freizeit":[],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"B\u00fcdchen an der U-Bahnhaltestelle Lister Platz,Jakobistra\u00dfe 2,30163 Hannover","loc_admin_google_place_id":"ChIJ0wgzLVRzsEcRXb8Gpzsfpqs","loc_admin_master_id":"1116"},"class_list":["post-34240","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/location\/34240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/media?parent=34240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}