{"id":35029,"date":"2025-04-28T13:34:06","date_gmt":"2025-04-28T11:34:06","guid":{"rendered":"https:\/\/hannover-living.de\/location\/amura\/"},"modified":"2025-07-04T07:58:06","modified_gmt":"2025-07-04T05:58:06","slug":"amura","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/pl\/location\/amura\/","title":{"rendered":"A'Mura"},"template":"","meta":{"loc_subtitle":"Ein Hauch von Italien","loc_beschreibung":"<p>Im A\u2018mura erh\u00e4lt man traditionelle Pizza, frische Pasta und so manche Delikatesse, mit denen das Mittelmeer nach <a href=\"https:\/\/hannover-living.de\/mitte\/\">Hannover<\/a> in Niedersachsen geholt wird. Die gro\u00dfe Au\u00dfenterrasse direkt an der Leine l\u00e4dt zum Verweilen ein. Genie\u00dfen Sie echte italienische Spezialit\u00e4ten und lassen Sie sich von einem exzellenten Service begeistern! Ebenfalls bietet das A\u2018mura in Hannover eine breite Auwahl bekannter und weniger bekannter Weine.<\/p>\n<p>Erleben Sie das A'mura in seinem neuen, einzigartigem Flair!<br \/>\nDas Restaurant besticht neben den neu gestalteten, gem\u00fctlichen R\u00e4umen mit der Freundlichkeit seines Services.<\/p>\n<p>\u00dcberzeugen Sie sich selbst von dem italienischen Restaurant in Hannover mit einem ganz besonderen Flair!<\/p>\n","loc_strasse":"Schlossstra\u00dfe","loc_hausnummer":"6","loc_plz":"30159","loc_ort":"Hannover","loc_google_maps":"A'Mura,Schlossstra\u00dfe 6,30159 Hannover","loc_telefonnummer":"","loc_stadtteil":"mitte","loc_teaserbild":"40893","loc_teasertext":"Entdecken Sie mediterrane K\u00f6stlichkeiten im A\u2018mura Hannover! Traditionelle Pizza, frische Pasta, erlesene Weine \u2013 direkt an der Leine. Genie\u00dfen Sie exzellenten Service in einzigartigem Flair!","loc_webseite":"https:\/\/www.a-mura.de\/","loc_360_link":"","loc_facebook":"https:\/\/www.facebook.com\/p\/Amura-100064896733944\/","loc_instagram":"https:\/\/www.instagram.com\/amura_hannover\/","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"true","loc_art_der_kueche":["italienische_kueche"],"loc_ambiente":"mediterranes Urlaubsfeeling","loc_switch_google_preisklasse":"false","loc_preisklasse":"\u20ac\u20ac","loc_unser_tipp":"Pizza & Pasta","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"true","loc_switch_open_show":"true","loc_open_montag":"11:30\u201322:00","loc_open_dienstag":"11:30\u201322:00","loc_open_mittwoch":"11:30\u201322:00","loc_open_donnerstag":"11:30\u201322:00","loc_open_freitag":"11:30\u201322:00","loc_open_samstag":"11:30\u201322:00","loc_open_sontag":"11:30\u201322:00","loc_nachhaltigkeit":"false","loc_galerie":[],"loc_location_art":["restaurant"],"loc_nightlife":[],"loc_freizeit":[],"loc_events_show":"false","loc_rest_show":"true","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"A'Mura,Schlossstra\u00dfe 6,30159 Hannover","loc_admin_google_place_id":"ChIJ7XP68e91sEcR7gdiUZ8EeZ8","loc_admin_master_id":"403"},"class_list":["post-35029","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/location\/35029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/pl\/wp-json\/wp\/v2\/media?parent=35029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}