{"id":34544,"date":"2025-04-28T12:52:50","date_gmt":"2025-04-28T10:52:50","guid":{"rendered":"https:\/\/hannover-living.de\/location\/biergarten-gretchen\/"},"modified":"2025-08-29T15:36:05","modified_gmt":"2025-08-29T13:36:05","slug":"%d0%bf%d0%b8%d0%b2%d0%bd%d0%b8%d0%b9-%d1%81%d0%b0%d0%b4-%d0%b3%d1%80%d0%b5%d1%82%d1%85%d0%b5%d0%bd","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/uk\/location\/biergarten-gretchen\/","title":{"rendered":"\u041f\u0438\u0432\u043d\u0438\u0439 \u0441\u0430\u0434 \"\u0413\u0440\u0435\u0442\u0445\u0435\u043d"},"template":"","meta":{"loc_subtitle":"Biergarten Gretchen","loc_beschreibung":"<p>Genie\u00dft den Sommer mit k\u00fchlen Getr\u00e4nken, Snacks, Burger und Pizzen im Biergarten Gretchen.<\/p>\n<p>Alle Veranstaltungen im Biergarten Gretchen findet ihr hier: <a href=\"https:\/\/www.biergarten-gretchen.de\/alle-veranstaltungen\">www.biergarten-gretchen.de\/alle-veranstaltungen<\/a><\/p>\n","loc_strasse":"Zur Bettfedernfabrik","loc_hausnummer":"3","loc_plz":"30451","loc_ort":"Hannover","loc_google_maps":"Biergarten Gretchen,Zur Bettfedernfabrik 3,30451 Hannover","loc_telefonnummer":"+49 511 124 68 \u2013 038","loc_stadtteil":"linden-nord","loc_teaserbild":"41724","loc_teasertext":"Genie\u00dft den Sommer mit k\u00fchlen Getr\u00e4nken, Snacks, Burger und Pizzen bei der Fu\u00dfball-Europameisterschaft 2024 im Biergarten Gretchen.","loc_webseite":"https:\/\/www.biergarten-gretchen.de\/","loc_360_link":"","loc_facebook":"","loc_instagram":"https:\/\/www.instagram.com\/biergarten_gretchen\/","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":["biergarten","burger_co"],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"false","loc_switch_open_show":"false","loc_open_montag":"","loc_open_dienstag":"","loc_open_mittwoch":"","loc_open_donnerstag":"","loc_open_freitag":"","loc_open_samstag":"","loc_open_sontag":"","loc_nachhaltigkeit":"false","loc_galerie":["https:\/\/hannover-living.de\/wp-content\/uploads\/2025\/04\/faust_fussball_em1.jpg","https:\/\/hannover-living.de\/wp-content\/uploads\/2025\/04\/faust_fussball_em2.jpg"],"loc_location_art":["restaurant"],"loc_nightlife":[],"loc_freizeit":[],"loc_events_show":"false","loc_rest_show":"true","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"gastro@kulturzentrum-faust.de","loc_admin_google_adress":"Biergarten Gretchen,Zur Bettfedernfabrik 3,30451 Hannover","loc_admin_google_place_id":"ChIJN999HIM5ZUER213BndYBrWk","loc_admin_master_id":"662"},"class_list":["post-34544","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/uk\/wp-json\/wp\/v2\/location\/34544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/uk\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/uk\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/uk\/wp-json\/wp\/v2\/media?parent=34544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}