{"id":35912,"date":"2025-05-01T13:42:06","date_gmt":"2025-05-01T11:42:06","guid":{"rendered":"https:\/\/hannover-living.de\/stadtteil\/misburg\/"},"modified":"2025-08-12T16:01:00","modified_gmt":"2025-08-12T14:01:00","slug":"%d0%bc%d1%96%d1%81%d0%b1%d1%83%d1%80%d0%b3","status":"publish","type":"stadtteil","link":"https:\/\/hannover-living.de\/uk\/stadtteil\/misburg\/","title":{"rendered":"\u041c\u0456\u0441\u0431\u0443\u0440\u0433"},"template":"","meta":{"dis_headerimage":"https:\/\/hannover-living.de\/wp-content\/uploads\/2025\/05\/Design-ohne-Titel187.png","dis_beschreibung":"Willkommen im Stadtteil Misburg!\r\nIm Osten Hannovers gelegen, verbindet Misburg urbanes Leben mit einer gr\u00fcnen Umgebung. Der Misburger Wald und der nahe Altwarmb\u00fcchener See bieten zahlreiche M\u00f6glichkeiten f\u00fcr Erholung und Freizeitaktivit\u00e4ten. Historische Wurzeln treffen hier auf moderne Wohngebiete und eine gewachsene Infrastruktur. Durch die gute Anbindung an die Innenstadt und die Vielfalt an Einkaufsm\u00f6glichkeiten ist Misburg ideal f\u00fcr alle, die stadtnah wohnen und gleichzeitig Natur genie\u00dfen m\u00f6chten.","dis_auswahl":"misburg-sued"},"class_list":["post-35912","stadtteil","type-stadtteil","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/uk\/wp-json\/wp\/v2\/stadtteil\/35912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/uk\/wp-json\/wp\/v2\/stadtteil"}],"about":[{"href":"https:\/\/hannover-living.de\/uk\/wp-json\/wp\/v2\/types\/stadtteil"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/uk\/wp-json\/wp\/v2\/media?parent=35912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}