{"id":35081,"date":"2025-04-28T13:34:20","date_gmt":"2025-04-28T11:34:20","guid":{"rendered":"https:\/\/hannover-living.de\/location\/niedersachsenhalle-im-hcc\/"},"modified":"2025-07-04T07:57:50","modified_gmt":"2025-07-04T05:57:50","slug":"%e4%b8%8b%e8%90%a8%e5%85%8b%e6%a3%ae%e5%a4%a7%e5%8e%85%e4%bd%8d%e4%ba%8ehcc","status":"publish","type":"location","link":"https:\/\/hannover-living.de\/zh\/location\/niedersachsenhalle-im-hcc\/","title":{"rendered":"HCC \u4e2d\u7684\u4e0b\u8428\u514b\u68ee\u5385"},"template":"","meta":{"loc_subtitle":"Vielseitige Veranstaltungsst\u00e4tte ","loc_beschreibung":"<p>Die Niedersachsenhalle im Hannover Congress Centrum (HCC) ist eine multifunktionale Veranstaltungshalle mit einer Gesamtfl\u00e4che von 1.627\u202fm\u00b2. Durch eine mobile Trennwand kann sie in zwei nahezu gleich gro\u00dfe Bereiche von 836\u202fm\u00b2 und 791\u202fm\u00b2 unterteilt werden. Die Halle bietet Platz f\u00fcr bis zu 1.512 Personen in Reihenbestuhlung und verf\u00fcgt \u00fcber eine fest eingebaute B\u00fchne sowie moderne Veranstaltungstechnik. Ein separater Eingangsbereich \u00fcber den Vorplatz des HCC und die N\u00e4he zu Parkh\u00e4usern erleichtern den Zugang f\u00fcr Besucher.<\/p>\n<h2>Technische Ausstattung und Nutzungsm\u00f6glichkeiten<\/h2>\n<ul>\n<li>Fl\u00e4che: 1.627\u202fm\u00b2<\/li>\n<li>Kapazit\u00e4t: Bis zu 1.512 Personen in Reihenbestuhlung<\/li>\n<li>Teilbarkeit: Zwei Hallenteile (836\u202fm\u00b2 und 791\u202fm\u00b2)<\/li>\n<li>B\u00fchne: Fest eingebaut, 77,83\u202fm\u00b2<\/li>\n<li>H\u00f6he: 5,40\u202fm<\/li>\n<li>H\u00e4ngepunkte: 18 mit je 500\u202fkg Traglast<\/li>\n<li>Zugang: Eigener Eingang, N\u00e4he zu Parkh\u00e4usern<\/li>\n<\/ul>\n<p>Die Niedersachsenhalle eignet sich f\u00fcr eine Vielzahl von Veranstaltungen, darunter Kongresse, Messen, Konzerte, Firmenfeiern und Ausstellungen. Die flexible Raumaufteilung und moderne Technik erm\u00f6glichen individuelle Veranstaltungskonzepte.<\/p>\n","loc_strasse":"Theodor-Heuss-Platz","loc_hausnummer":"23","loc_plz":"30175","loc_ort":"Hannover","loc_google_maps":"Niedersachsenhalle im HCC,Theodor-Heuss-Platz 23,30175 Hannover","loc_telefonnummer":"","loc_stadtteil":"zoo","loc_teaserbild":"35082","loc_teasertext":"Die Niedersachsenhalle, direkt am HCC, bietet als multifunktionale Veranstaltungs-Location unz\u00e4hlige M\u00f6glichkeiten f\u00fcr s\u00e4mtliche Veranstaltungsformate.","loc_webseite":"https:\/\/www.hcc.de\/raum\/niedersachsenhalle\/","loc_360_link":"","loc_facebook":"","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"true","loc_switch_open_show":"true","loc_open_montag":"11:00\u201318:00","loc_open_dienstag":"11:00\u201318:00","loc_open_mittwoch":"11:00\u201318:00","loc_open_donnerstag":"11:00\u201318:00","loc_open_freitag":"11:00\u201318:00","loc_open_samstag":"11:00\u201318:00","loc_open_sontag":"11:00\u201318:00","loc_nachhaltigkeit":"false","loc_galerie":[],"loc_location_art":["eventlocation"],"loc_nightlife":[],"loc_freizeit":["indoor","sehenswuerdigkeiten_highlights"],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"Niedersachsenhalle im HCC,Theodor-Heuss-Platz  23,30175  Hannover","loc_admin_google_place_id":"ChIJeQvd8FoLsEcR_v0AyiCtLLw","loc_admin_master_id":"145"},"class_list":["post-35081","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/zh\/wp-json\/wp\/v2\/location\/35081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/zh\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/hannover-living.de\/zh\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/zh\/wp-json\/wp\/v2\/media?parent=35081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}