{"id":35900,"date":"2025-05-01T13:41:48","date_gmt":"2025-05-01T11:41:48","guid":{"rendered":"https:\/\/hannover-living.de\/stadtteil\/ricklingen\/"},"modified":"2025-08-12T16:05:59","modified_gmt":"2025-08-12T14:05:59","slug":"%e9%87%8c%e5%85%8b%e6%9e%97%e6%a0%b9","status":"publish","type":"stadtteil","link":"https:\/\/hannover-living.de\/zh\/stadtteil\/ricklingen\/","title":{"rendered":"\u91cc\u514b\u6797\u6839"},"template":"","meta":{"dis_headerimage":"https:\/\/hannover-living.de\/wp-content\/uploads\/2025\/05\/Design-ohne-Titel181.png","dis_beschreibung":"Willkommen im Stadtteil Ricklingen!\r\nIm S\u00fcdwesten Hannovers gelegen, verbindet Ricklingen urbanes Leben mit naturnaher Erholung. Die Ricklinger Kiesteiche und die Leineaue laden zu Spazierg\u00e4ngen, Baden und sportlichen Aktivit\u00e4ten ein. Der Stadtteil bietet eine Mischung aus ruhigen Wohngebieten, guter Infrastruktur und kultureller Vielfalt. Dank der schnellen Anbindung an die Innenstadt ist Ricklingen ideal f\u00fcr alle, die stadtnah wohnen und gleichzeitig die Natur direkt vor der Haust\u00fcr genie\u00dfen m\u00f6chten.","dis_auswahl":"ricklingen"},"class_list":["post-35900","stadtteil","type-stadtteil","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hannover-living.de\/zh\/wp-json\/wp\/v2\/stadtteil\/35900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannover-living.de\/zh\/wp-json\/wp\/v2\/stadtteil"}],"about":[{"href":"https:\/\/hannover-living.de\/zh\/wp-json\/wp\/v2\/types\/stadtteil"}],"wp:attachment":[{"href":"https:\/\/hannover-living.de\/zh\/wp-json\/wp\/v2\/media?parent=35900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}